{"id":10191,"date":"2022-11-29T15:49:25","date_gmt":"2022-11-29T15:49:25","guid":{"rendered":"https:\/\/gtu.agency\/?p=10191"},"modified":"2022-11-29T15:56:20","modified_gmt":"2022-11-29T15:56:20","slug":"contentstrategie-fjallraven-swot-analyse","status":"publish","type":"post","link":"https:\/\/gtu.agency\/de\/contentstrategie-fjallraven-swot-analyse\/","title":{"rendered":"Die Contentstrategie von Fj\u00e4llr\u00e4ven: eine SWOT-Analyse"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Es ist Herbst, es ist dunkel und vielerorts nasskalt. Welche Kleidung sch\u00fctzt uns vor schlechtem Wetter?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sehen wir uns an, wie die Outdoor-Marke <\/span><a href=\"https:\/\/www.fjallraven.com\/de\/de-de\"><span style=\"font-weight: 400;\">Fj\u00e4llr\u00e4ven<\/span><\/a><span style=\"font-weight: 400;\"> mithilfe von Content Kunden f\u00fcr sich gewinnt.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Fj\u00e4llr\u00e4ven geh\u00f6rt zum schwedischen b\u00f6rsennotierten Unternehmen Fenix Outdoor International AG. Deutschland ist mit Abstand der wichtigste Absatzmarkt, noch vor dem Heimatland Schweden.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dort wurde Fj\u00e4llr\u00e4ven 1960 gegr\u00fcndet und hat sich seitdem auf die Herstellung von Outdoor-Ausr\u00fcstung und Funktionsbekleidung spezialisiert. Vor einigen Jahren hat Fj\u00e4llr\u00e4ven zudem das Sortiment um reine Lifestyleprodukte erweitert, z. B. die bunten K\u00e5nken Rucks\u00e4cke.<\/span><\/p>\n<h2><b>\u00dcbersicht<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Das Produktangebot ist wie folgt strukturiert:<\/span><\/p>\n<table>\n<tbody>\n<tr>\n<td><b>Herren<\/b><\/td>\n<td><b>Damen<\/b><\/td>\n<td><b>Taschen &amp; Ausr\u00fcstung<\/b><\/td>\n<td><b>Kinder<\/b><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400;\">Neuheiten<\/span><\/td>\n<td><span style=\"font-weight: 400;\">Neuheiten<\/span><\/td>\n<td><span style=\"font-weight: 400;\">Neuheiten<\/span><\/td>\n<td><span style=\"font-weight: 400;\">Neuheiten<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400;\">Jacken<\/span><\/td>\n<td><span style=\"font-weight: 400;\">Jacken<\/span><\/td>\n<td><span style=\"font-weight: 400;\">K\u00e5nken<\/span><\/td>\n<td><span style=\"font-weight: 400;\">Rucks\u00e4cke<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400;\">Hosen<\/span><\/td>\n<td><span style=\"font-weight: 400;\">Hosen<\/span><\/td>\n<td><span style=\"font-weight: 400;\">Rucks\u00e4cke &amp; Taschen<\/span><\/td>\n<td><span style=\"font-weight: 400;\">Jacken<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400;\">Oberteile<\/span><\/td>\n<td><span style=\"font-weight: 400;\">Oberteile<\/span><\/td>\n<td><span style=\"font-weight: 400;\">Accessoires<\/span><\/td>\n<td><span style=\"font-weight: 400;\">Hosen<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400;\">Accessoires<\/span><\/td>\n<td><span style=\"font-weight: 400;\">Accessoires<\/span><\/td>\n<td><span style=\"font-weight: 400;\">Zelte &amp; Schlafs\u00e4cke<\/span><\/td>\n<td><span style=\"font-weight: 400;\">Oberteile<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400;\">\u00a0<\/span><\/td>\n<td><span style=\"font-weight: 400;\">\u00a0<\/span><\/td>\n<td><span style=\"font-weight: 400;\">\u00a0<\/span><\/td>\n<td><span style=\"font-weight: 400;\">Accessoires<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Fj\u00e4llr\u00e4ven bietet die Produkte in 51 L\u00e4ndern an, im station\u00e4ren Handel sowie online. F\u00fcr die folgenden M\u00e4rkte gibt es jeweils eine \u00fcbersetzte Website: Deutschland, Finnland, Norwegen, D\u00e4nemark, Frankreich, Schweden, Niederlande, Gro\u00dfbritannien, Kanada, USA, S\u00fcdkorea.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Das Produktsortiment scheint \u00fcberall identisch zu sein, der Content im Blog-Bereich \u201eUnsere Abenteuer\u201c der \u00fcbersetzten Websites \u00e4ndert sich jedoch von Land zu Land. Beispielsweise sind im Foxtrail-Blog auf der Domain de-de 129 Blog-Seiten zu finden, auf der Domain gb-en fehlt \u201cFoxtrail\u201d, bzw. ist der entsprechende Content anscheinend unter Articles &gt; Adventures angeordnet.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Die Blog-Eintr\u00e4ge werden wahrscheinlich zentral verfasst und anschlie\u00dfend je nach Budget und Relevanz f\u00fcr die verschiedenen L\u00e4nder lokalisiert. Anschlie\u00dfend werden sie so auf der Website platziert, dass sie an den Suchgewohnheiten der Nutzer ausgerichtet sind.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Die Zielgruppen sind zum einen Outdoor-Begeisterte in eher \u00e4lteren Altersschichten, zum anderen modisch orientierte j\u00fcngere K\u00e4ufer (Rucksack K\u00e5nken). Beide Zielgruppen sch\u00e4tzen das schlichte Design und die gute Qualit\u00e4t, sind zahlungskr\u00e4ftig und suchen die Distinktion \u00fcber die Marke.<\/span><\/p>\n<h1><b>Analyse der Content-Strategie<\/b><\/h1>\n<p><span style=\"font-weight: 400;\">Der Content ist zielgruppenad\u00e4quat, weil er Kunden anspricht, die nicht nur ein Produkt kaufen wollen, sondern eine Marke, mit der sie sich identifizieren k\u00f6nnen. Die Inhalte sind durchweg so gestaltet, dass er mit den Kernwerten der Marke in Zusammenhang gebracht werden kann: authentisch anstatt k\u00fcnstlich, schlicht anstatt schrill, qualitativ hochwertig anstatt minderwertig. Zus\u00e4tzliche N\u00e4he wird durch Duzen der Kunden geschaffen.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Die Blog-Artikel unter \u201eFj\u00e4llr\u00e4ven Experience &gt; Foxtrail\u201c sprechen verschiedene Schwerpunkte an und sind verschlagwortet, d. h. man kann \u00fcber entsprechende Buttons Artikel zu Abenteuern, Tipps, Nachhaltigkeit und Produkten aufrufen. Die meisten Artikel gibt es zu Produkten.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Der Content unter \u201eFj\u00e4llr\u00e4ven Experience &gt; Classic\u201c und \u201eFj\u00e4llr\u00e4ven Experience &gt; Polar\u201c bezieht sich auf Trekking-Events, die von Fj\u00e4llr\u00e4ven organisiert werden. Die Content-Strategie zielt hier eindeutig darauf ab, <\/span><i><span style=\"font-weight: 400;\">warum<\/span><\/i><span style=\"font-weight: 400;\"> es das Unternehmen Fj\u00e4llr\u00e4ven gibt. Die Produkte stehen im Hintergrund und werden so pr\u00e4sentiert, als w\u00e4ren sie die logische Konsequenz aus dem <\/span><i><span style=\"font-weight: 400;\">Warum<\/span><\/i><span style=\"font-weight: 400;\"> des Unternehmens (Simonek 2009).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Der Content entlang der Customer Journey ist auf verschiedenen Kan\u00e4len verf\u00fcgbar. Der wahrscheinlich wichtigste Kanal f\u00fcr Neukunden ist der erste Stimulus durch die Sichtbarkeit der bunten K\u00e5nken Rucks\u00e4cke im \u00f6ffentlichen Raum. Es gibt eine gro\u00dfe Menge an User-Generated Content zu diesem Produkt auf YouTube \u2013 Produkttests, Hintergrundberichte usw. \u2013 mit weitaus mehr Ansichten und Abonnenten als auf dem offiziellen Fj\u00e4llr\u00e4ven-Kanal.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Zudem hat Fj\u00e4llr\u00e4ven dedizierte Kan\u00e4le auf YouTube, Facebook und Instagram, wo sich Kunden inspirieren lassen und ihre Journey beginnen k\u00f6nnen.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Besonders hervorzuheben ist der Instagram-Kanal \u201ekankenofficial\u201c, wo Fj\u00e4llr\u00e4ven die Kunden einspannt, um die Brand zu bewerben (\u201eTag your posts with #Kanken for a chance to be featured.\u201c)<\/span><\/p>\n<h2><b>FISH-Content<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Fj\u00e4llr\u00e4ven nutzt <\/span><b>F<\/b><span style=\"font-weight: 400;\">ollow-Content auf Instagram, Facebook und YouTube. Speziell im YouTube-Kanal gibt es beispielsweise kleinere Dokumentationen, Produktanleitungen usw., die das Interesse bei potenziellen K\u00e4ufern aufrechterhalten.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Interessierte Kunden haben die M\u00f6glichkeit, nach Ansehen des Follow-Contents einen Newsletter auf der Website zu abonnieren. So kann Fj\u00e4llr\u00e4ven Content anbieten, der sich an Kunden richtet, die zumindest an den Produkten interessiert sind. Dadurch k\u00f6nnen <\/span><b>I<\/b><span style=\"font-weight: 400;\">nbound-Leads generiert werden.<\/span><\/p>\n<p><b>S<\/b><span style=\"font-weight: 400;\">earch- und Sales-Content beschr\u00e4nkt sich auf die Bereitstellung von Informationen \u00fcber bestimmte Produkte. Beispielsweise ist die Website mit SEO so aufbereitet, dass in Google nach Eingabe von \u201eTrekkinghose wachsen\u201c auf Seite 1 der Suchergebnisse ein Link zu einer relevanten Fj\u00e4llr\u00e4ven-Seite angezeigt wird.<\/span><\/p>\n<p><b>H<\/b><span style=\"font-weight: 400;\">ighlight-Content findet sich vorwiegend auf Instagram und YouTube bzw. ist auf der Website verlinkt. Auf Instagram sind dies beispielsweise kurze Videoclips, die zum Umweltschutz aufrufen (\u201eCan you change the world in 2 minutes?\u201c; Instagram-Account 2minutebeachclean). Auf YouTube w\u00e4re dies z. B. ein Video \u00fcber das Leave No Trace Center for Outdoor Ethics.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Der anschlie\u00dfende Kauf kann direkt auf Instagram erfolgen, wo der K\u00e4ufer zum Einkaufsbereich auf der Website weitergeleitet wird. \u00dcber Facebook und YouTube gelangt man lediglich auf die Website, nicht in den Einkaufsbereich.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Storytelling findet man im Bereich \u201eFj\u00e4llr\u00e4ven Experience &gt; Polar\/Classic\u201c, wo Videos \u00fcber Trekkingevents zu sehen sind. Dort wird ein bestimmtes Lebensgef\u00fchl beschrieben, das die Kunden durch den Kauf der Produkte erleben sollen.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Das Content-Marketing von Fj\u00e4llr\u00e4ven ist eher skandinavisch zur\u00fcckhaltend und passt somit zum <\/span><i><span style=\"font-weight: 400;\">Warum<\/span><\/i><span style=\"font-weight: 400;\"> des Unternehmens. Dies kommt auch im Instagram-Hashtag #natureiswaiting zum Ausdruck: Das Individuum steht im Hintergrund, wichtiger scheint das aktive Erleben der Natur, wobei Ausr\u00fcstung und Kleidung dieses Erleben erm\u00f6glichen.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Fj\u00e4llr\u00e4ven produziert die Inhalte selbst, z. B. Produktvideos und -fotos sowie Dokumentationen \u00fcber die \u201eUnsere Abenteuer\u201c-Events, und publiziert sie in den unternehmenseigenen Kan\u00e4len. Das Unternehmen profitiert jedoch auch enorm von User-Generated Content.<\/span><\/p>\n<h1><b>Mitbewerber<\/b><\/h1>\n<p><span style=\"font-weight: 400;\">Ein Mitwerber ist z. B. The North Face (https:\/\/www.thenorthface.de\/).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">The North Face tritt wesentlich aggressiver auf und das Sortiment erstreckt sich abgesehen von Outdoor-Equipment auch auf die Bereiche Lifestyle, Running, Wintersport, Schuhe. Dementsprechend breiter aufgestellt ist auch der Content. Dieser umfasst Berichte \u00fcber Veranstaltungen wie z. B. The North Face Mountain Festival und Tomorrowland Winter sowie Berichte \u00fcber Athleten, vermutlich im Rahmen eines Sponsorvertrags.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Die Content-Strategie von The North Face ist \u2013 wie auch das Produktportfolio \u2013 wesentlich umfangreicher als das von Fj\u00e4llr\u00e4ven. Es wird mehr Wert auf Highlight-Content gelegt und allgemein steht das Individuum und das amerikanische Streben zur n\u00e4chsten Frontier (\u201eNever Stop Exploring\u201c) im Vordergrund. Vom Erleben der Natur wie bei Fj\u00e4llr\u00e4ven ist so gut wie keine Rede.<\/span><\/p>\n<h1><b>SWOT-Analyse der aktuellen Content Strategie<\/b><\/h1>\n<p><span style=\"font-weight: 400;\">Als SWOT-Analyse bezeichnet man die Ermittlung der St\u00e4rken, Schw\u00e4chen, Chancen und Risiken eines Unternehmens oder einer Marke. Aus dem Ergebnis der Analyse lassen sich weitere Schritte ableiten, z. B. eine Neuausrichtung im Online-Marketing.<\/span><\/p>\n<table>\n<tbody>\n<tr>\n<td><b>St\u00e4rken (<\/b><b>S<\/b><b>trengths)<\/b><\/p>\n<p><span style=\"font-weight: 400;\">\u00b7<\/span><span style=\"font-weight: 400;\"> \u00a0 <\/span> <span style=\"font-weight: 400;\">Marke<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00b7<\/span><span style=\"font-weight: 400;\"> \u00a0 <\/span> <span style=\"font-weight: 400;\">Preisf\u00fchrerschaft<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00b7<\/span><span style=\"font-weight: 400;\"> \u00a0 <\/span> <span style=\"font-weight: 400;\">Kunden kaufen das <\/span><i><span style=\"font-weight: 400;\">Warum<\/span><\/i><span style=\"font-weight: 400;\">, das durch die Content-Strategie vermittelt wird<\/span><\/td>\n<td><b>Schw\u00e4chen (<\/b><b>W<\/b><b>eaknesses)<\/b><\/p>\n<p><span style=\"font-weight: 400;\">\u00b7<\/span><span style=\"font-weight: 400;\"> \u00a0 <\/span> <span style=\"font-weight: 400;\">Content spricht nicht den Massenmarkt an (Ausnahme: K\u00e5nken)<\/span><\/td>\n<\/tr>\n<tr>\n<td><b>Chancen (<\/b><b>O<\/b><b>pportunities)<\/b><\/p>\n<p><span style=\"font-weight: 400;\">\u00b7<\/span><span style=\"font-weight: 400;\"> \u00a0 \u00a0 \u00a0 <\/span><span style=\"font-weight: 400;\">Thematischer Ausbau des Highlight-Contents<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00b7<\/span><span style=\"font-weight: 400;\"> \u00a0 \u00a0 \u00a0 <\/span><span style=\"font-weight: 400;\">Internationalisierung, d. h. Erschlie\u00dfen neuer Absatzm\u00e4rkte durch Lokalisierung des Contents (z. B. Japan)<\/span><\/td>\n<td><b>Risiken (<\/b><b>T<\/b><b>hreats)<\/b><\/p>\n<p><span style=\"font-weight: 400;\">\u00b7<\/span><span style=\"font-weight: 400;\"> \u00a0 <\/span> <span style=\"font-weight: 400;\">Stagnation bzgl. eingeschr\u00e4nktes Produktportfolio<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00b7<\/span><span style=\"font-weight: 400;\"> \u00a0 <\/span> <span style=\"font-weight: 400;\">Falsche Wachstumsstrategie und dadurch Erosion von Marke und Preisf\u00fchrerschaft<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00b7<\/span><span style=\"font-weight: 400;\"> \u00a0 <\/span> <span style=\"font-weight: 400;\">Kunden k\u00f6nnen abspringen<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h1><b>Ausblick<\/b><\/h1>\n<p><span style=\"font-weight: 400;\">In Anlehnung an das eigentliche Mission Statement (\u201eDie Menschen inspirieren, im Einklang mit der Natur zu leben\u201c), k\u00f6nnte das neue <em>Content Mission Statement<\/em> wie folgt lauten:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201eWir bieten Menschen Kleidung und Ausr\u00fcstung, um im Einklang mit der Natur zu leben. Wir glauben, dass Zeit in der Natur das Leben bereichert und ein ureigenes Bed\u00fcrfnis ist. Deshalb wollen wir Produkte erschaffen, die zeitlos und langlebig sind und dich auf deinen Reisen und Abenteuern begleiten.\u201c<\/span><\/p>\n<h1><b>Quellen:<\/b><\/h1>\n<p><span style=\"font-weight: 400;\">Simonek, S. (2009): How great leaders inspire action (<\/span><a href=\"https:\/\/www.ted.com\/talks\/simon_sinek_how_great_leaders_inspire_action?language=de\"><span style=\"font-weight: 400;\">https:\/\/www.ted.com\/talks\/simon_sinek_how_great_leaders_inspire_action?language=de<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es ist Herbst, es ist dunkel und vielerorts nasskalt. Welche Kleidung sch\u00fctzt uns vor schlechtem Wetter? Sehen wir uns an, wie die Outdoor-Marke Fj\u00e4llr\u00e4ven mithilfe von Content Kunden f\u00fcr sich gewinnt. Fj\u00e4llr\u00e4ven geh\u00f6rt zum schwedischen b\u00f6rsennotierten Unternehmen Fenix Outdoor International AG. Deutschland ist mit Abstand der wichtigste Absatzmarkt, noch vor dem Heimatland Schweden. Dort wurde &#8230; <a title=\"Die Contentstrategie von Fj\u00e4llr\u00e4ven: eine SWOT-Analyse\" class=\"read-more\" href=\"https:\/\/gtu.agency\/de\/contentstrategie-fjallraven-swot-analyse\/\" aria-label=\"Mehr Informationen \u00fcber Die Contentstrategie von Fj\u00e4llr\u00e4ven: eine SWOT-Analyse\">Weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":10197,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-10191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Contentstrategie von Fj\u00e4llr\u00e4ven: eine SWOT-Analyse - GTU<\/title>\n<meta name=\"description\" content=\"Erfahre mehr dar\u00fcber, welchen Content Fj\u00e4llr\u00e4ven erstellt und welche St\u00e4rken, Schw\u00e4chen, Chancen und Risiken (SWOT) es gibt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gtu.agency\/de\/contentstrategie-fjallraven-swot-analyse\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Contentstrategie von Fj\u00e4llr\u00e4ven: eine SWOT-Analyse - GTU\" \/>\n<meta property=\"og:description\" content=\"Erfahre mehr dar\u00fcber, welchen Content Fj\u00e4llr\u00e4ven erstellt und welche St\u00e4rken, Schw\u00e4chen, Chancen und Risiken (SWOT) es gibt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gtu.agency\/de\/contentstrategie-fjallraven-swot-analyse\/\" \/>\n<meta property=\"og:site_name\" content=\"GTU\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-29T15:49:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-29T15:56:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/11\/fjall-raven-content-strategie_hires.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"612\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Veit\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Veit\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gtu.agency\\\/de\\\/contentstrategie-fjallraven-swot-analyse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gtu.agency\\\/de\\\/contentstrategie-fjallraven-swot-analyse\\\/\"},\"author\":{\"name\":\"Veit\",\"@id\":\"https:\\\/\\\/gtu.agency\\\/#\\\/schema\\\/person\\\/0bb491ff56ad5c07cd0946a2b1da8abf\"},\"headline\":\"Die Contentstrategie von Fj\u00e4llr\u00e4ven: eine SWOT-Analyse\",\"datePublished\":\"2022-11-29T15:49:25+00:00\",\"dateModified\":\"2022-11-29T15:56:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gtu.agency\\\/de\\\/contentstrategie-fjallraven-swot-analyse\\\/\"},\"wordCount\":1284,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/gtu.agency\\\/#\\\/schema\\\/person\\\/f0aa70d9acb47d7aeba5fbcf24aaf0ba\"},\"image\":{\"@id\":\"https:\\\/\\\/gtu.agency\\\/de\\\/contentstrategie-fjallraven-swot-analyse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gtu.agency\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/fjall-raven-content-strategie_hires.jpg\",\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gtu.agency\\\/de\\\/contentstrategie-fjallraven-swot-analyse\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gtu.agency\\\/de\\\/contentstrategie-fjallraven-swot-analyse\\\/\",\"url\":\"https:\\\/\\\/gtu.agency\\\/de\\\/contentstrategie-fjallraven-swot-analyse\\\/\",\"name\":\"Die Contentstrategie von Fj\u00e4llr\u00e4ven: eine SWOT-Analyse - GTU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gtu.agency\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gtu.agency\\\/de\\\/contentstrategie-fjallraven-swot-analyse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gtu.agency\\\/de\\\/contentstrategie-fjallraven-swot-analyse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gtu.agency\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/fjall-raven-content-strategie_hires.jpg\",\"datePublished\":\"2022-11-29T15:49:25+00:00\",\"dateModified\":\"2022-11-29T15:56:20+00:00\",\"description\":\"Erfahre mehr dar\u00fcber, welchen Content Fj\u00e4llr\u00e4ven erstellt und welche St\u00e4rken, Schw\u00e4chen, Chancen und Risiken (SWOT) es gibt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gtu.agency\\\/de\\\/contentstrategie-fjallraven-swot-analyse\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gtu.agency\\\/de\\\/contentstrategie-fjallraven-swot-analyse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/gtu.agency\\\/de\\\/contentstrategie-fjallraven-swot-analyse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gtu.agency\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/fjall-raven-content-strategie_hires.jpg\",\"contentUrl\":\"https:\\\/\\\/gtu.agency\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/fjall-raven-content-strategie_hires.jpg\",\"width\":1000,\"height\":612,\"caption\":\"Ein Abenteurer mit einem Cowboy-Hut, den Blick zum Horizont gerichtet\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gtu.agency\\\/de\\\/contentstrategie-fjallraven-swot-analyse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/gtu.agency\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Contentstrategie von Fj\u00e4llr\u00e4ven: eine SWOT-Analyse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gtu.agency\\\/#website\",\"url\":\"https:\\\/\\\/gtu.agency\\\/\",\"name\":\"GTU\",\"description\":\"Translation Agency\",\"publisher\":{\"@id\":\"https:\\\/\\\/gtu.agency\\\/#\\\/schema\\\/person\\\/f0aa70d9acb47d7aeba5fbcf24aaf0ba\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gtu.agency\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/gtu.agency\\\/#\\\/schema\\\/person\\\/f0aa70d9acb47d7aeba5fbcf24aaf0ba\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/gtu.agency\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/icon-gtu.svg\",\"url\":\"https:\\\/\\\/gtu.agency\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/icon-gtu.svg\",\"contentUrl\":\"https:\\\/\\\/gtu.agency\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/icon-gtu.svg\",\"width\":120,\"height\":65,\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/gtu.agency\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/icon-gtu.svg\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gtu.agency\\\/#\\\/schema\\\/person\\\/0bb491ff56ad5c07cd0946a2b1da8abf\",\"name\":\"Veit\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc9a63149ccb0487eaeba13fd44cd92ca3743bc974df7ae38c2f892167a40876?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc9a63149ccb0487eaeba13fd44cd92ca3743bc974df7ae38c2f892167a40876?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc9a63149ccb0487eaeba13fd44cd92ca3743bc974df7ae38c2f892167a40876?s=96&d=mm&r=g\",\"caption\":\"Veit\"},\"url\":\"https:\\\/\\\/gtu.agency\\\/de\\\/author\\\/gtu05\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Contentstrategie von Fj\u00e4llr\u00e4ven: eine SWOT-Analyse - GTU","description":"Erfahre mehr dar\u00fcber, welchen Content Fj\u00e4llr\u00e4ven erstellt und welche St\u00e4rken, Schw\u00e4chen, Chancen und Risiken (SWOT) es gibt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gtu.agency\/de\/contentstrategie-fjallraven-swot-analyse\/","og_locale":"de_DE","og_type":"article","og_title":"Die Contentstrategie von Fj\u00e4llr\u00e4ven: eine SWOT-Analyse - GTU","og_description":"Erfahre mehr dar\u00fcber, welchen Content Fj\u00e4llr\u00e4ven erstellt und welche St\u00e4rken, Schw\u00e4chen, Chancen und Risiken (SWOT) es gibt.","og_url":"https:\/\/gtu.agency\/de\/contentstrategie-fjallraven-swot-analyse\/","og_site_name":"GTU","article_published_time":"2022-11-29T15:49:25+00:00","article_modified_time":"2022-11-29T15:56:20+00:00","og_image":[{"width":1000,"height":612,"url":"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/11\/fjall-raven-content-strategie_hires.jpg","type":"image\/jpeg"}],"author":"Veit","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Veit","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gtu.agency\/de\/contentstrategie-fjallraven-swot-analyse\/#article","isPartOf":{"@id":"https:\/\/gtu.agency\/de\/contentstrategie-fjallraven-swot-analyse\/"},"author":{"name":"Veit","@id":"https:\/\/gtu.agency\/#\/schema\/person\/0bb491ff56ad5c07cd0946a2b1da8abf"},"headline":"Die Contentstrategie von Fj\u00e4llr\u00e4ven: eine SWOT-Analyse","datePublished":"2022-11-29T15:49:25+00:00","dateModified":"2022-11-29T15:56:20+00:00","mainEntityOfPage":{"@id":"https:\/\/gtu.agency\/de\/contentstrategie-fjallraven-swot-analyse\/"},"wordCount":1284,"commentCount":1,"publisher":{"@id":"https:\/\/gtu.agency\/#\/schema\/person\/f0aa70d9acb47d7aeba5fbcf24aaf0ba"},"image":{"@id":"https:\/\/gtu.agency\/de\/contentstrategie-fjallraven-swot-analyse\/#primaryimage"},"thumbnailUrl":"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/11\/fjall-raven-content-strategie_hires.jpg","articleSection":["Unkategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gtu.agency\/de\/contentstrategie-fjallraven-swot-analyse\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gtu.agency\/de\/contentstrategie-fjallraven-swot-analyse\/","url":"https:\/\/gtu.agency\/de\/contentstrategie-fjallraven-swot-analyse\/","name":"Die Contentstrategie von Fj\u00e4llr\u00e4ven: eine SWOT-Analyse - GTU","isPartOf":{"@id":"https:\/\/gtu.agency\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gtu.agency\/de\/contentstrategie-fjallraven-swot-analyse\/#primaryimage"},"image":{"@id":"https:\/\/gtu.agency\/de\/contentstrategie-fjallraven-swot-analyse\/#primaryimage"},"thumbnailUrl":"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/11\/fjall-raven-content-strategie_hires.jpg","datePublished":"2022-11-29T15:49:25+00:00","dateModified":"2022-11-29T15:56:20+00:00","description":"Erfahre mehr dar\u00fcber, welchen Content Fj\u00e4llr\u00e4ven erstellt und welche St\u00e4rken, Schw\u00e4chen, Chancen und Risiken (SWOT) es gibt.","breadcrumb":{"@id":"https:\/\/gtu.agency\/de\/contentstrategie-fjallraven-swot-analyse\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gtu.agency\/de\/contentstrategie-fjallraven-swot-analyse\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/gtu.agency\/de\/contentstrategie-fjallraven-swot-analyse\/#primaryimage","url":"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/11\/fjall-raven-content-strategie_hires.jpg","contentUrl":"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/11\/fjall-raven-content-strategie_hires.jpg","width":1000,"height":612,"caption":"Ein Abenteurer mit einem Cowboy-Hut, den Blick zum Horizont gerichtet"},{"@type":"BreadcrumbList","@id":"https:\/\/gtu.agency\/de\/contentstrategie-fjallraven-swot-analyse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/gtu.agency\/de\/"},{"@type":"ListItem","position":2,"name":"Die Contentstrategie von Fj\u00e4llr\u00e4ven: eine SWOT-Analyse"}]},{"@type":"WebSite","@id":"https:\/\/gtu.agency\/#website","url":"https:\/\/gtu.agency\/","name":"GTU","description":"Translation Agency","publisher":{"@id":"https:\/\/gtu.agency\/#\/schema\/person\/f0aa70d9acb47d7aeba5fbcf24aaf0ba"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gtu.agency\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/gtu.agency\/#\/schema\/person\/f0aa70d9acb47d7aeba5fbcf24aaf0ba","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/03\/icon-gtu.svg","url":"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/03\/icon-gtu.svg","contentUrl":"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/03\/icon-gtu.svg","width":120,"height":65,"caption":"admin"},"logo":{"@id":"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/03\/icon-gtu.svg"}},{"@type":"Person","@id":"https:\/\/gtu.agency\/#\/schema\/person\/0bb491ff56ad5c07cd0946a2b1da8abf","name":"Veit","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/cc9a63149ccb0487eaeba13fd44cd92ca3743bc974df7ae38c2f892167a40876?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cc9a63149ccb0487eaeba13fd44cd92ca3743bc974df7ae38c2f892167a40876?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cc9a63149ccb0487eaeba13fd44cd92ca3743bc974df7ae38c2f892167a40876?s=96&d=mm&r=g","caption":"Veit"},"url":"https:\/\/gtu.agency\/de\/author\/gtu05\/"}]}},"_links":{"self":[{"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/posts\/10191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/comments?post=10191"}],"version-history":[{"count":2,"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/posts\/10191\/revisions"}],"predecessor-version":[{"id":10196,"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/posts\/10191\/revisions\/10196"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/media\/10197"}],"wp:attachment":[{"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/media?parent=10191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/categories?post=10191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/tags?post=10191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}