{"id":10157,"date":"2022-11-23T16:17:06","date_gmt":"2022-11-23T16:17:06","guid":{"rendered":"https:\/\/gtu.agency\/?p=10157"},"modified":"2022-11-25T07:30:03","modified_gmt":"2022-11-25T07:30:03","slug":"wie-schwer-ist-der-job-eines-uebersetzers","status":"publish","type":"post","link":"https:\/\/gtu.agency\/de\/wie-schwer-ist-der-job-eines-uebersetzers\/","title":{"rendered":"Wie schwer ist der Job eines \u00dcbersetzers?"},"content":{"rendered":"<p>Die Frage m\u00fcsste man eigentlich anders stellen, und zwar: \u201cWie schwer ist der Job eines \u00dcbersetzers <em>heute<\/em>?\u201d Die T\u00e4tigkeiten eines \u00dcbersetzers haben sich n\u00e4mlich im Informationszeitalter fundamental ge\u00e4ndert.<\/p>\n<p>Wie in vielen anderen Branchen auch, hielten der PC und das Internet nicht \u00fcber Nacht Einzug ins Arbeitsleben, sondern Schritt f\u00fcr Schritt. Wenn man sich heute vergegenw\u00e4rtigt, was man als \u00dcbersetzer eigentlich tut, kann man sich vor Unglauben nur die Augen reiben.<\/p>\n<p>In diesem Artikel erkunden wir, was freiberufliche \u00dcbersetzer eigentlich tun, wie sich ihre T\u00e4tigkeiten im Laufe der Zeit ge\u00e4ndert haben und was die Zukunft bringt.<\/p>\n<h2>Ausbildung und Aufgaben von \u00dcbersetzern<\/h2>\n<p>Man kann \u00dcbersetzen an Fachhochschulen und Universit\u00e4ten studieren oder sich an privaten Instituten zum staatlich gepr\u00fcften \u00dcbersetzer ausbilden lassen. Genaueres kann man beim <a href=\"https:\/\/bdue.de\/der-beruf\/wege-zum-beruf\">BD\u00dc<\/a> (Bundesverband der Dolmetscher und \u00dcbersetzer) erfahren.<\/p>\n<p>Abgesehen von den offiziellen Ausbildungswegen gibt es weiterhin sehr viele Quereinsteiger, d. h. \u00dcbersetzer, die sich gut in einem Sachgebiet, z. B. klinischen Studien, auskennen und dieses Fachwissen in den Beruf einbringen.<\/p>\n<p>Wichtig ist, dass \u00dcbersetzer \u2013 mit Ausnahme der Bezeichnung \u201cVereidigter \u00dcbersetzer\u201d \u2013 keine gesch\u00fctzte Berufsbezeichnung ist. Es darf sich also fast jeder \u00dcbersetzer nennen, der sich dazu berufen f\u00fchlt.<\/p>\n<p>\u00dcbersetzer arbeiten in den wenigsten F\u00e4llen fest angestellt, z. B. in Gro\u00dfunternehmen oder bei der EU. Die meisten \u00dcbersetzer arbeiten als Freiberufler, und um die Freiberufler geht es vorrangig in diesem Artikel.<\/p>\n<h2>Fr\u00fcher war alles besser<\/h2>\n<p>War es das wirklich?<\/p>\n<p>Vor der massenweisen Verbreitung des PCs wurde noch mit Hilfe der Schreibmaschine \u00fcbersetzt. Das Gleiche galt f\u00fcr die Dokumentenerstellung auf der Auftraggeberseite, z. B. in der Abteilung f\u00fcr Technische Redaktion.<\/p>\n<p>Wie z\u00e4hlte man die W\u00f6rter in solchen Dokumenten, um ein Angebot zu erstellen? Einer meiner fr\u00fcheren Chefs hat es mir verraten: \u201cIrgendwann, es waren die 70er Jahre, hatten wir keine Lust mehr, die W\u00f6rter per Hand zu z\u00e4hlen. Wir haben die ausgedruckten Dokumente dann einfach auf die Waage gelegt und die W\u00f6rter anhand von Erfahrungswerten gesch\u00e4tzt.\u201d Clever.<\/p>\n<p><a href=\"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/11\/Imagen-2.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-10160 size-full\" src=\"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/11\/Imagen-2.png\" alt=\"\" width=\"977\" height=\"977\" srcset=\"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/11\/Imagen-2.png 977w, https:\/\/gtu.agency\/wp-content\/uploads\/2022\/11\/Imagen-2-300x300.png 300w, https:\/\/gtu.agency\/wp-content\/uploads\/2022\/11\/Imagen-2-150x150.png 150w, https:\/\/gtu.agency\/wp-content\/uploads\/2022\/11\/Imagen-2-768x768.png 768w\" sizes=\"(max-width: 977px) 100vw, 977px\" \/><\/a><\/p>\n<p>Quelle: Erstellt durch K\u00fcnstliche Intelligenz auf Midjourney<\/p>\n<p>Dann kamen die PCs und Anfang der 90er dann auch das erste Translation Memory. Nach den PCs kam Ende der 90er Jahre dann das Internet bzw. erst einmal E-Mails. Man musste zumindest zum Liefern der Auftr\u00e4ge keine Disketten mehr per Kurier verschicken. Das World Wide Web war allerdings im Vergleich zu heute noch so gut wie leer.<\/p>\n<p>\u00dcbersetzungsagenturen waren damals noch voller W\u00f6rterb\u00fccher und Referenzliteratur. Es wurde noch telefoniert. Die Leute gingen ins B\u00fcro. Es war vielleicht etwas gem\u00fctlicher.<\/p>\n<p>Das Internet, so wie wir es heute kennen, l\u00e4sst die Vergangenheit wie ein M\u00e4rchen erscheinen.<\/p>\n<h2>Digitalisierung<\/h2>\n<p>PC und Internet, also das, was man heute unter dem Begriff \u201cDigitalisierung\u201d zusammenfasst, haben die T\u00e4tigkeiten von \u00dcbersetzern ma\u00dfgeblich ver\u00e4ndert.<\/p>\n<p>Es gibt die Legende vom Frosch, der in einem Beh\u00e4lter mit Wasser sitzt. Erhitzt man das Wasser langsam bis zum Siedepunkt, verkocht er. Erhitzt man das Wasser rasch, springt er aus dem Beh\u00e4lter und rettet er sich.<\/p>\n<p>\u00c4hnlich kann man die Entwicklung seit den 80er Jahren deuten, wobei der technische Wandel die Wassertemperatur ist. Einige \u00dcbersetzer machen so weiter wie bisher, andere passen sich den Zeitl\u00e4uften an.<\/p>\n<p>Werfen wir nun einen Blick darauf, was \u00dcbersetzer tun und was heute anders ist als fr\u00fcher.<\/p>\n<p>&nbsp;<\/p>\n<h3>Schreiben<\/h3>\n<p>Hier geht es um die Textproduktion. Fr\u00fcher mit Schreibmaschine oder Computer, in jedem Fall manuell durch Eintippen der Buchstaben.<\/p>\n<p>Heute gibt es Spracherkennungsprogramme (speech to text), die die gesprochene \u00dcbersetzung automatisch in Text umwandeln.<\/p>\n<p>Die maschinelle \u00dcbersetzung (\u201cMachine Translation\u201d) wiederum gibt die \u00dcbersetzung vor, der \u00dcbersetzer passt sie dann nunmehr an und agiert somit als Lektor.<\/p>\n<p>Oder das CAT-Tool erkennt, welches Wort man eintippen will und macht Vorschl\u00e4ge f\u00fcr die Vervollst\u00e4ndigung der Eingabe.<\/p>\n<p>Bye-bye Tastatur?<\/p>\n<p>&nbsp;<\/p>\n<h3>Recherchieren<\/h3>\n<p>Was fr\u00fcher die Bibliothek war, ist heute Google bzw. das Internet. Dauerte es fr\u00fcher Stunden, bevor man einer Benennung in der Zielsprache auf die Spur kam, kann man dies heute in Sekunden oder Minuten erledigen.<\/p>\n<p>Das \u00dcberangebot an Informationen im Internet ist allerdings Fluch und Segen zugleich: Man muss in der Lage sein, rasch das Wichtige vom Unwichtigen zu trennen.<\/p>\n<p>Fundierte Kenntnisse in einem Sachbereich sind deshalb nach wie vor ein wichtiges Alleinstellungsmerkmal f\u00fcr \u00dcbersetzer.<\/p>\n<p>&nbsp;<\/p>\n<h3>Dateien \u00fcbertragen<\/h3>\n<p>Ich selbst habe noch die Diskettenzeit bis Ende der 90er erlebt. Danach kam E-Mail und danach FTP (File Transfer Protocol). Heute werden Dateien h\u00e4ufig \u00fcber Portale \u00fcbertragen, z. B. XTRF und Plunet, wo die gelieferten Dateien direkt in einen Workflow eingespeist werden.<\/p>\n<p>Die Betreiber dieser Portale, in den meisten F\u00e4llen \u00dcbersetzungsagenturen, profitieren davon, weil ein Portal die Automatisierung von Workflows erlaubt. Dateien werden sicher \u00fcbertragen und durch die Abbildung einzelner Prozessschritte im Workflow werden \u00dcbersetzungsprojekte personenunabh\u00e4ngiger. Das Prozessrisiko sinkt.<\/p>\n<p>&nbsp;<\/p>\n<h3>Qualit\u00e4t pr\u00fcfen<\/h3>\n<p>Wenn man als Nicht-\u00dcbersetzer an die Qualit\u00e4tskontrolle denkt, hat man evtl. die manuelle Pr\u00fcfung, also ein einfaches Durchlesen vor Augen. Die Realit\u00e4t sieht heute aber anders aus: Absolut unverzichtbar sind die \u00fcber die Taste F7 aufrufbare Rechtschreib- und Grammatikkontrolle in MS Word, die QA-Module in den \u00dcbersetzungstools und schlie\u00dflich externe QA-Tools wie z. B. Xbench oder Verifika.<\/p>\n<p>Tippfehler und Zahlendreher kommen vor. Es gibt aber heute keine Entschuldigung mehr daf\u00fcr, wenn es Tools gibt, die diese Fehler automatisch erkennen.<\/p>\n<p>&nbsp;<\/p>\n<h3>Kunden akquirieren<\/h3>\n<p>Wenn man sein eigenes Kaufverhalten analysiert, stellt man fest, dass man in vielen F\u00e4llen zun\u00e4chst im Internet sucht und recherchiert. Zumal bei gr\u00f6\u00dferen Anschaffungen. Die Suche erfolgt zun\u00e4chst planlos und wird dann gezielter. Die potenziellen Kunden von \u00dcbersetzern gehen genauso vor.<\/p>\n<p>\u00dcbersetzer sollten demnach dar\u00fcber nachdenken, eine Onlinepr\u00e4senz aufzubauen, damit sie von Kunden gefunden werden k\u00f6nnen. Allerdings: Weil Tausende von \u00dcbersetzerprofilen online verf\u00fcgbar sind steigt der Differenzierungsdruck, und das regelm\u00e4\u00dfige Posten auf LinkedIn, Twitter usw. kann viel Zeit verschlingen.<\/p>\n<p>Das Stichwort hier ist \u201cSocial Proof\u201d, was sich darauf bezieht, dass Menschen eher etwas kaufen, wenn jemand anders sich positiv dar\u00fcber \u00e4u\u00dfert und gewisserma\u00dfen den Beweis daf\u00fcr liefert, dass dem Dienstleister zu vertrauen ist.<\/p>\n<p>&nbsp;<\/p>\n<h3>Abrechnen<\/h3>\n<p>Viele \u00dcbersetzer sind noch mit Excel und PDFs unterwegs. Alternativen dazu sind Online-Buchhaltungsprogramme, in denen Rechnungen erstellt werden und Kunden an die Zahlung der Rechnung erinnert werden k\u00f6nnen.<\/p>\n<p>Manche Kunden berichten davon, wie sp\u00e4t einige \u00dcbersetzer ihre Rechnungen schicken, bzw. einige schicken sie gar nicht. Das wirkt sich auf die Reputation des \u00dcbersetzers und logischerweise auf die Liquidit\u00e4t aus.<\/p>\n<p>&nbsp;<\/p>\n<h3>Weiterbildung<\/h3>\n<p>Wie oben erw\u00e4hnt, sind Fachkenntnisse ein wichtiges Alleinstellungsmerkmal. H\u00e4ufig sind dazu keine gro\u00dfen Investitionen n\u00f6tig, abgesehen von der Zeit, die man investieren muss. Auf Coursera, Udacity, edX sowie beim <a href=\"https:\/\/bdue.de\/der-bdue\/leistungen\/weiterbildung\">BD\u00dc<\/a> gibt es ein vielf\u00e4ltiges Angebot, z. B. diesen <a href=\"https:\/\/www.coursera.org\/learn\/diabetes-essential-facts?action=enroll\">Kurs \u00fcber Diabetes auf Coursera<\/a>.<\/p>\n<p>Der Kreis schlie\u00dft sich \u00fcber Social Media, wo man das erlernte Wissen auf seinem Profil hinterlegen und somit f\u00fcr Kunden sichtbar machen kann.<\/p>\n<p>&nbsp;<\/p>\n<h2>Was bringt die Zukunft?<\/h2>\n<p>Man kann davon ausgehen, dass die Qualit\u00e4t der maschinellen \u00dcbersetzung besser wird. Zudem werden neue Sprachkombinationen hinzukommen. \u00dcbersetzer werden also in Zukunft weniger aktiv \u00fcbersetzen, sondern sich wahrscheinlich eher in Richtung Qualit\u00e4tskontrolle entwickeln.<\/p>\n<p>Andere Berufszweige sind bereits so hoch entwickelt, dass manuelle Abl\u00e4ufe gar nicht mehr vorstellbar sind, z. B. in der Landwirtschaft und Fertigung, die bereits einen hohen Automatisierungsgrad erreicht haben.<\/p>\n<p>Zudem sprechen die Investitionen in K\u00fcnstliche Intelligenz eine deutliche Sprache: Die Investitionen in KI sind zwischen 2013 und 2021 um das 35-Fache gestiegen.<\/p>\n<p><a href=\"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/11\/Imagen-1.png\"><img decoding=\"async\" class=\"aligncenter wp-image-10163 size-full\" src=\"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/11\/Imagen-1.png\" alt=\"\" width=\"977\" height=\"689\" srcset=\"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/11\/Imagen-1.png 977w, https:\/\/gtu.agency\/wp-content\/uploads\/2022\/11\/Imagen-1-300x212.png 300w, https:\/\/gtu.agency\/wp-content\/uploads\/2022\/11\/Imagen-1-768x542.png 768w\" sizes=\"(max-width: 977px) 100vw, 977px\" \/><\/a><\/p>\n<p>Quelle: <a href=\"https:\/\/ourworldindata.org\/grapher\/corporate-investment-in-artificial-intelligence-by-type?country=Merger%2FAcquisition~Private+Investment~Minority+Stake~Public+Offering\">Our World in Data<\/a><\/p>\n<p>Investoren wollen nat\u00fcrlich Rendite und deshalb kann man davon ausgehen, dass die Resultate dieser Investitionsprojekte in Gesch\u00e4ftsmodelle einflie\u00dfen und diese revolutionieren werden, darunter auch Gesch\u00e4ftsmodelle in der \u00dcbersetzungsbranche.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Frage m\u00fcsste man eigentlich anders stellen, und zwar: \u201cWie schwer ist der Job eines \u00dcbersetzers heute?\u201d Die T\u00e4tigkeiten eines \u00dcbersetzers haben sich n\u00e4mlich im Informationszeitalter fundamental ge\u00e4ndert. Wie in vielen anderen Branchen auch, hielten der PC und das Internet nicht \u00fcber Nacht Einzug ins Arbeitsleben, sondern Schritt f\u00fcr Schritt. Wenn man sich heute vergegenw\u00e4rtigt, &#8230; <a title=\"Wie schwer ist der Job eines \u00dcbersetzers?\" class=\"read-more\" href=\"https:\/\/gtu.agency\/de\/wie-schwer-ist-der-job-eines-uebersetzers\/\" aria-label=\"Mehr Informationen \u00fcber Wie schwer ist der Job eines \u00dcbersetzers?\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":10167,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-10157","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Best Practices f\u00fcr Untertitel auf YouTube<\/title>\n<meta name=\"description\" content=\"Die Konkurrenz auf YouTube wird immer h\u00e4rter. \u00dcbersetzte Untertitel k\u00f6nnen die Reichweite steigern. Wir stellen einige Best Practices vor.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gtu.agency\/de\/wie-schwer-ist-der-job-eines-uebersetzers\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Best Practices f\u00fcr Untertitel auf YouTube\" \/>\n<meta property=\"og:description\" content=\"Die Konkurrenz auf YouTube wird immer h\u00e4rter. \u00dcbersetzte Untertitel k\u00f6nnen die Reichweite steigern. Wir stellen einige Best Practices vor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gtu.agency\/de\/wie-schwer-ist-der-job-eines-uebersetzers\/\" \/>\n<meta property=\"og:site_name\" content=\"GTU\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-23T16:17:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-25T07:30:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/11\/Ubersetzer_lores.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gtu.agency\\\/de\\\/wie-schwer-ist-der-job-eines-uebersetzers\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gtu.agency\\\/de\\\/wie-schwer-ist-der-job-eines-uebersetzers\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/gtu.agency\\\/#\\\/schema\\\/person\\\/f0aa70d9acb47d7aeba5fbcf24aaf0ba\"},\"headline\":\"Wie schwer ist der Job eines \u00dcbersetzers?\",\"datePublished\":\"2022-11-23T16:17:06+00:00\",\"dateModified\":\"2022-11-25T07:30:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gtu.agency\\\/de\\\/wie-schwer-ist-der-job-eines-uebersetzers\\\/\"},\"wordCount\":1300,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gtu.agency\\\/#\\\/schema\\\/person\\\/f0aa70d9acb47d7aeba5fbcf24aaf0ba\"},\"image\":{\"@id\":\"https:\\\/\\\/gtu.agency\\\/de\\\/wie-schwer-ist-der-job-eines-uebersetzers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gtu.agency\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Ubersetzer_lores.png\",\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gtu.agency\\\/de\\\/wie-schwer-ist-der-job-eines-uebersetzers\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gtu.agency\\\/de\\\/wie-schwer-ist-der-job-eines-uebersetzers\\\/\",\"url\":\"https:\\\/\\\/gtu.agency\\\/de\\\/wie-schwer-ist-der-job-eines-uebersetzers\\\/\",\"name\":\"Best Practices f\u00fcr Untertitel auf YouTube\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gtu.agency\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gtu.agency\\\/de\\\/wie-schwer-ist-der-job-eines-uebersetzers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gtu.agency\\\/de\\\/wie-schwer-ist-der-job-eines-uebersetzers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gtu.agency\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Ubersetzer_lores.png\",\"datePublished\":\"2022-11-23T16:17:06+00:00\",\"dateModified\":\"2022-11-25T07:30:03+00:00\",\"description\":\"Die Konkurrenz auf YouTube wird immer h\u00e4rter. \u00dcbersetzte Untertitel k\u00f6nnen die Reichweite steigern. Wir stellen einige Best Practices vor.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gtu.agency\\\/de\\\/wie-schwer-ist-der-job-eines-uebersetzers\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gtu.agency\\\/de\\\/wie-schwer-ist-der-job-eines-uebersetzers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/gtu.agency\\\/de\\\/wie-schwer-ist-der-job-eines-uebersetzers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gtu.agency\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Ubersetzer_lores.png\",\"contentUrl\":\"https:\\\/\\\/gtu.agency\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Ubersetzer_lores.png\",\"width\":1200,\"height\":627},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gtu.agency\\\/de\\\/wie-schwer-ist-der-job-eines-uebersetzers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/gtu.agency\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wie schwer ist der Job eines \u00dcbersetzers?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gtu.agency\\\/#website\",\"url\":\"https:\\\/\\\/gtu.agency\\\/\",\"name\":\"GTU\",\"description\":\"Translation Agency\",\"publisher\":{\"@id\":\"https:\\\/\\\/gtu.agency\\\/#\\\/schema\\\/person\\\/f0aa70d9acb47d7aeba5fbcf24aaf0ba\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gtu.agency\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/gtu.agency\\\/#\\\/schema\\\/person\\\/f0aa70d9acb47d7aeba5fbcf24aaf0ba\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/gtu.agency\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/icon-gtu.svg\",\"url\":\"https:\\\/\\\/gtu.agency\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/icon-gtu.svg\",\"contentUrl\":\"https:\\\/\\\/gtu.agency\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/icon-gtu.svg\",\"width\":120,\"height\":65,\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/gtu.agency\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/icon-gtu.svg\"},\"url\":\"https:\\\/\\\/gtu.agency\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Best Practices f\u00fcr Untertitel auf YouTube","description":"Die Konkurrenz auf YouTube wird immer h\u00e4rter. \u00dcbersetzte Untertitel k\u00f6nnen die Reichweite steigern. Wir stellen einige Best Practices vor.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gtu.agency\/de\/wie-schwer-ist-der-job-eines-uebersetzers\/","og_locale":"de_DE","og_type":"article","og_title":"Best Practices f\u00fcr Untertitel auf YouTube","og_description":"Die Konkurrenz auf YouTube wird immer h\u00e4rter. \u00dcbersetzte Untertitel k\u00f6nnen die Reichweite steigern. Wir stellen einige Best Practices vor.","og_url":"https:\/\/gtu.agency\/de\/wie-schwer-ist-der-job-eines-uebersetzers\/","og_site_name":"GTU","article_published_time":"2022-11-23T16:17:06+00:00","article_modified_time":"2022-11-25T07:30:03+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/11\/Ubersetzer_lores.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gtu.agency\/de\/wie-schwer-ist-der-job-eines-uebersetzers\/#article","isPartOf":{"@id":"https:\/\/gtu.agency\/de\/wie-schwer-ist-der-job-eines-uebersetzers\/"},"author":{"name":"admin","@id":"https:\/\/gtu.agency\/#\/schema\/person\/f0aa70d9acb47d7aeba5fbcf24aaf0ba"},"headline":"Wie schwer ist der Job eines \u00dcbersetzers?","datePublished":"2022-11-23T16:17:06+00:00","dateModified":"2022-11-25T07:30:03+00:00","mainEntityOfPage":{"@id":"https:\/\/gtu.agency\/de\/wie-schwer-ist-der-job-eines-uebersetzers\/"},"wordCount":1300,"commentCount":0,"publisher":{"@id":"https:\/\/gtu.agency\/#\/schema\/person\/f0aa70d9acb47d7aeba5fbcf24aaf0ba"},"image":{"@id":"https:\/\/gtu.agency\/de\/wie-schwer-ist-der-job-eines-uebersetzers\/#primaryimage"},"thumbnailUrl":"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/11\/Ubersetzer_lores.png","articleSection":["Unkategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gtu.agency\/de\/wie-schwer-ist-der-job-eines-uebersetzers\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gtu.agency\/de\/wie-schwer-ist-der-job-eines-uebersetzers\/","url":"https:\/\/gtu.agency\/de\/wie-schwer-ist-der-job-eines-uebersetzers\/","name":"Best Practices f\u00fcr Untertitel auf YouTube","isPartOf":{"@id":"https:\/\/gtu.agency\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gtu.agency\/de\/wie-schwer-ist-der-job-eines-uebersetzers\/#primaryimage"},"image":{"@id":"https:\/\/gtu.agency\/de\/wie-schwer-ist-der-job-eines-uebersetzers\/#primaryimage"},"thumbnailUrl":"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/11\/Ubersetzer_lores.png","datePublished":"2022-11-23T16:17:06+00:00","dateModified":"2022-11-25T07:30:03+00:00","description":"Die Konkurrenz auf YouTube wird immer h\u00e4rter. \u00dcbersetzte Untertitel k\u00f6nnen die Reichweite steigern. Wir stellen einige Best Practices vor.","breadcrumb":{"@id":"https:\/\/gtu.agency\/de\/wie-schwer-ist-der-job-eines-uebersetzers\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gtu.agency\/de\/wie-schwer-ist-der-job-eines-uebersetzers\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/gtu.agency\/de\/wie-schwer-ist-der-job-eines-uebersetzers\/#primaryimage","url":"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/11\/Ubersetzer_lores.png","contentUrl":"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/11\/Ubersetzer_lores.png","width":1200,"height":627},{"@type":"BreadcrumbList","@id":"https:\/\/gtu.agency\/de\/wie-schwer-ist-der-job-eines-uebersetzers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/gtu.agency\/de\/"},{"@type":"ListItem","position":2,"name":"Wie schwer ist der Job eines \u00dcbersetzers?"}]},{"@type":"WebSite","@id":"https:\/\/gtu.agency\/#website","url":"https:\/\/gtu.agency\/","name":"GTU","description":"Translation Agency","publisher":{"@id":"https:\/\/gtu.agency\/#\/schema\/person\/f0aa70d9acb47d7aeba5fbcf24aaf0ba"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gtu.agency\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/gtu.agency\/#\/schema\/person\/f0aa70d9acb47d7aeba5fbcf24aaf0ba","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/03\/icon-gtu.svg","url":"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/03\/icon-gtu.svg","contentUrl":"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/03\/icon-gtu.svg","width":120,"height":65,"caption":"admin"},"logo":{"@id":"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/03\/icon-gtu.svg"},"url":"https:\/\/gtu.agency\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/posts\/10157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/comments?post=10157"}],"version-history":[{"count":3,"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/posts\/10157\/revisions"}],"predecessor-version":[{"id":10178,"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/posts\/10157\/revisions\/10178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/media\/10167"}],"wp:attachment":[{"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/media?parent=10157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/categories?post=10157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/tags?post=10157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}