{"id":1944,"date":"2022-06-23T13:54:49","date_gmt":"2022-06-23T13:54:49","guid":{"rendered":"https:\/\/gtu.agency\/terms-and-conditions-of-use\/"},"modified":"2022-07-11T08:29:18","modified_gmt":"2022-07-11T08:29:18","slug":"allgemeine-nutzungsbedingungen","status":"publish","type":"page","link":"https:\/\/gtu.agency\/de\/allgemeine-nutzungsbedingungen\/","title":{"rendered":"Allgemeine Nutzungsbedingungen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1944\" class=\"elementor elementor-1944 elementor-1685\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8b61713 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8b61713\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-14f03ae\" data-id=\"14f03ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-928fb61 elementor-widget elementor-widget-heading\" data-id=\"928fb61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Allgemeine Nutzungsbedingungen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cef2a89 elementor-widget elementor-widget-text-editor\" data-id=\"cef2a89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"padding-left: 40px;\"><strong>1.&nbsp; &nbsp; &nbsp; Einf\u00fchrung<\/strong><\/p>\n<p>1.1&nbsp;&nbsp;&nbsp; Diese allgemeinen Nutzungsbedingungen regeln Ihre Nutzung unserer Website.<\/p>\n<p>1.2&nbsp;&nbsp;&nbsp; Durch die Nutzung unserer Website akzeptieren Sie diese allgemeinen Nutzungsbedingungen in vollem Umfang; dementsprechend d\u00fcrfen Sie unsere Website nicht nutzen, wenn Sie mit diesen Bedingungen oder einem Teil dieser Bedingungen nicht einverstanden sind.<\/p>\n<p>1.3&nbsp;&nbsp;&nbsp; Wenn Sie sich auf unserer Website registrieren, Material an unsere Website \u00fcbermitteln oder einen unserer Websitedienste nutzen, werden wir Sie auffordern, diesen allgemeinen Nutzungsbedingungen ausdr\u00fccklich zuzustimmen.<\/p>\n<p style=\"padding-left: 40px;\"><strong>2. Copyright-Hinweis<\/strong><\/p>\n<p>2.1&nbsp;&nbsp;&nbsp; Copyright (c) 2021 German Translation Unit.<\/p>\n<p>2.2&nbsp;&nbsp;&nbsp; Vorbehaltlich der ausdr\u00fccklichen Bestimmungen der vorliegenden allgemeinen Nutzungsbedingungen:<\/p>\n<p>(a)&nbsp;&nbsp;&nbsp; besitzen und kontrollieren wir, zusammen mit unseren Lizenzgebern, alle Urheberrechte und anderen geistigen Eigentumsrechte an unserer Website und dem Material auf unserer Website und<\/p>\n<p>(b)&nbsp;&nbsp;&nbsp; sind alle Urheberrechte und sonstigen geistigen Eigentumsrechte an unserer Website und dem Material auf unserer Website vorbehalten.<\/p>\n<p style=\"padding-left: 40px;\"><strong>3. Erlaubnis zur Nutzung der Website<\/strong><\/p>\n<p>3.1&nbsp;&nbsp;&nbsp; Sie k\u00f6nnen:<\/p>\n<p>(a)&nbsp;&nbsp;&nbsp; die Seiten unserer Website in einem Webbrowser ansehen,<\/p>\n<p>(b)&nbsp;&nbsp;&nbsp; Seiten von unserer Website zum Zwischenspeichern in einem Webbrowser herunterladen,<\/p>\n<p>(c)&nbsp;&nbsp;&nbsp; Seiten unserer Website f\u00fcr den pers\u00f6nlichen und nicht kommerziellen Gebrauch ausdrucken, vorausgesetzt, dass dies nicht systematisch oder \u00fcberm\u00e4\u00dfig geschieht,<\/p>\n<p>(d)&nbsp;&nbsp;&nbsp; unsere Website-Dienste mit Hilfe eines Webbrowsers nutzen,<\/p>\n<p>vorbehaltlich der \u00fcbrigen Bestimmungen der vorliegenden allgemeinen Nutzungsbedingungen.<\/p>\n<p>3.2&nbsp;&nbsp;&nbsp; Sofern nicht ausdr\u00fccklich durch Abschnitt 3.1 oder die anderen Bestimmungen dieser allgemeinen Nutzungsbedingungen gestattet, d\u00fcrfen Sie kein Material von unserer Website herunterladen oder auf Ihrem Computer speichern.<\/p>\n<p>3.3&nbsp;&nbsp;&nbsp; Sie d\u00fcrfen unsere Website nur f\u00fcr Ihre eigenen pers\u00f6nlichen und gesch\u00e4ftlichen Zwecke nutzen; Sie d\u00fcrfen unsere Website nicht f\u00fcr andere Zwecke verwenden.<\/p>\n<p>3.4&nbsp;&nbsp;&nbsp; Sofern nicht ausdr\u00fccklich durch diese allgemeinen Nutzungsbedingungen gestattet, d\u00fcrfen Sie kein Material auf unserer Website bearbeiten oder anderweitig ver\u00e4ndern.<\/p>\n<p>3.5&nbsp;&nbsp;&nbsp; Sofern Sie nicht die entsprechenden Rechte an dem Material besitzen oder kontrollieren, d\u00fcrfen Sie Folgendes nicht:<\/p>\n<p>(a)&nbsp;&nbsp;&nbsp; Material von unserer Website erneut ver\u00f6ffentlichen (einschlie\u00dflich Wiederver\u00f6ffentlichung auf einer anderen Website),<\/p>\n<p>(b)&nbsp;&nbsp;&nbsp; Material von unserer Website verkaufen, vermieten oder unterlizenzieren,<\/p>\n<p>(c)&nbsp;&nbsp;&nbsp; Material von unserer Website in der \u00d6ffentlichkeit zeigen,<\/p>\n<p>(d)&nbsp;&nbsp;&nbsp; Material von unserer Website f\u00fcr einen kommerziellen Zweck nutzen oder<\/p>\n<p>(e)&nbsp;&nbsp;&nbsp; Material von unserer Website weiterverbreiten.<\/p>\n<p>3.6&nbsp;&nbsp;&nbsp; Ungeachtet Abschnitt 3.5 d\u00fcrfen Sie unseren Newsletter in gedruckter und elektronischer Form an jede Person weitergeben.<\/p>\n<p>3.7&nbsp;&nbsp;&nbsp; Wir behalten uns das Recht vor, den Zugang zu unserer Website, zu Bereichen unserer Website und\/oder zu Funktionen auf unserer Website auszusetzen oder einzuschr\u00e4nken. Wir k\u00f6nnen zum Beispiel den Zugang zur Website w\u00e4hrend der Wartung des Servers oder bei der Aktualisierung der Website aussetzen. Sie d\u00fcrfen keine Zugangsbeschr\u00e4nkungsma\u00dfnahmen auf der Website umgehen oder versuchen, diese zu umgehen.<\/p>\n<p style=\"padding-left: 40px;\"><strong>4. Missbr\u00e4uchliche Nutzung der Website<\/strong><\/p>\n<p>4.1&nbsp;&nbsp;&nbsp; Sie d\u00fcrfen Folgendes nicht tun:<\/p>\n<p>(a)&nbsp;&nbsp;&nbsp; unsere Website in irgendeiner Weise nutzen oder Handlungen vornehmen, die Sch\u00e4den an der Website oder eine Beeintr\u00e4chtigung der Leistung, Verf\u00fcgbarkeit, Zug\u00e4nglichkeit, Integrit\u00e4t oder Sicherheit der Website verursachen oder verursachen k\u00f6nnen,<\/p>\n<p>(b)&nbsp;&nbsp;&nbsp; unsere Website in einer Weise nutzen, die ungesetzlich, illegal, betr\u00fcgerisch oder sch\u00e4dlich ist, oder in Verbindung mit einem ungesetzlichen, illegalen, betr\u00fcgerischen oder sch\u00e4dlichen Zweck oder einer Aktivit\u00e4t steht,<\/p>\n<p>(c)&nbsp;&nbsp;&nbsp; unsere Website hacken oder anderweitig manipulieren,<\/p>\n<p>(d)&nbsp;&nbsp;&nbsp; die Anf\u00e4lligkeit unserer Website ohne unsere Erlaubnis untersuchen, scannen oder testen,<\/p>\n<p>(e)&nbsp;&nbsp;&nbsp; Authentifizierungs- oder Sicherheitssysteme oder -verfahren auf oder im Zusammenhang mit unserer Website umgehen,<\/p>\n<p>(f)&nbsp;&nbsp;&nbsp; unsere Website nutzen, um Material zu kopieren, zu speichern, zu hosten, zu \u00fcbertragen, zu senden, zu verwenden, zu ver\u00f6ffentlichen oder zu verteilen, das aus Spyware, Computerviren, Trojanern, W\u00fcrmern, Keystroke-Loggern, Rootkits oder anderer b\u00f6sartiger Computersoftware besteht (oder damit verbunden ist),<\/p>\n<p>(g)&nbsp;&nbsp;&nbsp; die Ressourcen unserer Website (einschlie\u00dflich Bandbreite, Speicherkapazit\u00e4t und Verarbeitungskapazit\u00e4t) unangemessen stark belasten,<\/p>\n<p>(h)&nbsp;&nbsp;&nbsp; Mitteilungen, die von unserer oder an unsere Website gesendet werden, ohne unsere Zustimmung entschl\u00fcsseln oder entziffern,<\/p>\n<p>(i)&nbsp;&nbsp;&nbsp;&nbsp; systematische oder automatisierte Datenerfassungsaktivit\u00e4ten (einschlie\u00dflich, aber nicht beschr\u00e4nkt auf Scraping, Data Mining, Datenextraktion und Data Harvesting) auf oder in Bezug auf unsere Website ohne unsere ausdr\u00fcckliche schriftliche Zustimmung durchf\u00fchren,<\/p>\n<p>(j)&nbsp;&nbsp;&nbsp;&nbsp; mit Hilfe von Robotern, Spidern oder anderen automatisierten Mitteln auf unsere Website zugreifen oder anderweitig mit ihr interagieren, au\u00dfer zum Zweck der Indizierung durch Suchmaschinen,<\/p>\n<p>(k)&nbsp;&nbsp;&nbsp; unsere Website verwenden, au\u00dfer \u00fcber unsere \u00f6ffentlichen Schnittstellen,<\/p>\n<p>(l)&nbsp;&nbsp;&nbsp;&nbsp; gegen die in der robots.txt-Datei f\u00fcr unsere Website festgelegten Richtlinien versto\u00dfen,<\/p>\n<p>(m)&nbsp;&nbsp; die auf unserer Website gesammelten Daten f\u00fcr Direktmarketing-Aktivit\u00e4ten verwenden (einschlie\u00dflich, aber nicht beschr\u00e4nkt auf E-Mail-Marketing, SMS-Marketing, Telefonmarketing und Direktwerbung) oder<\/p>\n<p>(n)&nbsp;&nbsp;&nbsp; irgendetwas tun, das die normale Nutzung unserer Website st\u00f6rt.<\/p>\n<p>4.2 Sie d\u00fcrfen die auf unserer Website gesammelten Daten nicht verwenden, um mit Einzelpersonen, Unternehmen oder anderen Personen oder Einrichtungen Kontakt aufzunehmen.<\/p>\n<p>4.3&nbsp;&nbsp;&nbsp; Sie m\u00fcssen sicherstellen, dass alle Informationen, die Sie uns \u00fcber unsere Website oder im Zusammenhang mit unserer Website zur Verf\u00fcgung stellen, wahr, genau, aktuell, vollst\u00e4ndig und nicht irref\u00fchrend sind.<\/p>\n<p style=\"padding-left: 40px;\"><strong>5. Registrierung und Konten<\/strong><\/p>\n<p>5.2&nbsp;&nbsp;&nbsp; Sie k\u00f6nnen sich f\u00fcr ein Konto auf unserer Website registrieren, indem Sie das Formular zur Kontoregistrierung auf unserer Website ausf\u00fcllen und abschicken und auf den Verifizierungslink in der E-Mail klicken, die Ihnen von der Website zugesandt wird.<\/p>\n<p>5.3&nbsp;&nbsp;&nbsp; Sie d\u00fcrfen keiner anderen Person erlauben, Ihr Konto f\u00fcr den Zugang zur Website zu nutzen.<\/p>\n<p>5.4&nbsp;&nbsp;&nbsp; Sie m\u00fcssen uns unverz\u00fcglich schriftlich benachrichtigen, wenn Sie von einer unbefugten Nutzung Ihres Kontos Kenntnis erlangen.<\/p>\n<p>5.5&nbsp;&nbsp;&nbsp; Sie d\u00fcrfen das Konto einer anderen Person nicht f\u00fcr den Zugriff auf die Website verwenden, es sei denn, Sie haben die ausdr\u00fcckliche Erlaubnis dieser Person.<\/p>\n<p style=\"padding-left: 40px;\"><strong>6. Benutzer-Anmeldedaten<\/strong><\/p>\n<p>6.1&nbsp;&nbsp;&nbsp; Wenn Sie sich f\u00fcr ein Konto auf unserer Website registrieren, stellen wir Ihnen eine Benutzer-ID und ein Passwort zur Verf\u00fcgung oder Sie werden aufgefordert, diese zu w\u00e4hlen.<\/p>\n<p>6.2&nbsp;&nbsp;&nbsp; Ihre Benutzerkennung darf nicht zur Irref\u00fchrung geeignet sein und muss den in Abschnitt 9 dargelegten Inhaltsregeln entsprechen; Sie d\u00fcrfen Ihr Konto oder Ihre Benutzerkennung nicht f\u00fcr oder in Verbindung mit der Nachahmung einer Person verwenden.<\/p>\n<p>6.3&nbsp;&nbsp;&nbsp; Sie m\u00fcssen Ihr Passwort geheim halten.<\/p>\n<p>6.4&nbsp;&nbsp;&nbsp; Sie m\u00fcssen uns unverz\u00fcglich schriftlich benachrichtigen, wenn Sie von einer Offenlegung Ihres Passworts erfahren.<\/p>\n<p>6.5&nbsp;&nbsp;&nbsp; Sie sind f\u00fcr alle Aktivit\u00e4ten auf unserer Website verantwortlich, die sich aus einem Vers\u00e4umnis ergeben, Ihr Passwort geheim zu halten, und k\u00f6nnen f\u00fcr alle Verluste haftbar gemacht werden, die sich aus einem solchen Vers\u00e4umnis ergeben.<\/p>\n<p style=\"padding-left: 40px;\"><strong>7. L\u00f6schung und Aussetzung des Kontos<\/strong><\/p>\n<p>7.1&nbsp;&nbsp;&nbsp; Wir d\u00fcrfen:<\/p>\n<p>(a)&nbsp;&nbsp;&nbsp; Ihr Konto sperren,<\/p>\n<p>(b)&nbsp;&nbsp;&nbsp; Ihr Konto l\u00f6schen und\/oder<\/p>\n<p>(c)&nbsp;&nbsp;&nbsp; Ihre Kontodaten bearbeiten,<\/p>\n<p>jederzeit nach unserem alleinigen Ermessen mit oder ohne Mitteilung an Sie.<\/p>\n<p>7.2&nbsp;&nbsp;&nbsp; In der Regel k\u00fcndigen wir ein Konto, wenn es \u00fcber einen ununterbrochenen Zeitraum von 18 Monaten ungenutzt bleibt.<\/p>\n<p>7.3&nbsp;&nbsp;&nbsp; Sie k\u00f6nnen Ihr Konto auf unserer Website \u00fcber Ihren Konto-Kontrollbereich auf der Website l\u00f6schen.<\/p>\n<p style=\"padding-left: 40px;\"><strong>8. Unsere Rechte zur Nutzung Ihrer Inhalte<\/strong><\/p>\n<p>8.1&nbsp;&nbsp;&nbsp; In diesen allgemeinen Nutzungsbedingungen bezeichnet \u201eIhr Inhalt\u201c alle Werke und Materialien (einschlie\u00dflich, aber nicht beschr\u00e4nkt auf Texte, Grafiken, Bilder, Audiomaterial, Videomaterial, audiovisuelles Material, Skripte, Software und Dateien), die Sie uns oder unserer Website zur Speicherung oder Ver\u00f6ffentlichung auf unserer Website, zur Verarbeitung durch unsere Website oder zur \u00dcbertragung \u00fcber unsere Website \u00fcbermitteln.<\/p>\n<p>8.2&nbsp;&nbsp;&nbsp; Sie gew\u00e4hren uns eine weltweite, unwiderrufliche, nicht-exklusive, geb\u00fchrenfreie Lizenz zur Nutzung, Vervielf\u00e4ltigung, Speicherung, Anpassung, Ver\u00f6ffentlichung, \u00dcbersetzung und Verbreitung Ihrer Inhalte in allen bestehenden oder zuk\u00fcnftigen Medien ODER zur Vervielf\u00e4ltigung, Speicherung und Ver\u00f6ffentlichung Ihrer Inhalte auf dieser und in Bezug auf diese Website und jede Nachfolge-Website ODER zur Vervielf\u00e4ltigung, Speicherung und, mit Ihrer ausdr\u00fccklichen Zustimmung, Ver\u00f6ffentlichung Ihrer Inhalte auf dieser und in Bezug auf diese Website.<\/p>\n<p>8.3&nbsp;&nbsp;&nbsp; Sie r\u00e4umen uns das Recht ein, Unterlizenzen f\u00fcr die gem\u00e4\u00df Abschnitt 8.2 lizenzierten Rechte zu vergeben.<\/p>\n<p>8.4&nbsp;&nbsp;&nbsp; Sie r\u00e4umen uns das Recht ein, eine Klage wegen Verletzung der unter Ziffer 8.2 lizenzierten Rechte zu erheben.<\/p>\n<p>8.5&nbsp;&nbsp;&nbsp; Sie verzichten hiermit auf alle moralischen Rechte an Ihren Inhalten, soweit dies nach geltendem Recht zul\u00e4ssig ist, und Sie garantieren und sichern zu, dass auf alle anderen moralischen Rechte an Ihren Inhalten verzichtet wurde, soweit dies nach geltendem Recht zul\u00e4ssig ist.<\/p>\n<p>8.6&nbsp;&nbsp;&nbsp; Sie k\u00f6nnen Ihre Inhalte im zul\u00e4ssigen Umfang mit den auf unserer Website zur Verf\u00fcgung gestellten Bearbeitungsfunktionen bearbeiten.<\/p>\n<p>8.7&nbsp;&nbsp;&nbsp; Unbeschadet unserer sonstigen Rechte gem\u00e4\u00df diesen allgemeinen Nutzungsbedingungen k\u00f6nnen wir, wenn Sie gegen eine Bestimmung dieser Bedingungen versto\u00dfen oder wenn wir den begr\u00fcndeten Verdacht haben, dass Sie gegen diese Bedingungen versto\u00dfen haben, Ihre Inhalte ganz oder teilweise l\u00f6schen, nicht mehr ver\u00f6ffentlichen oder bearbeiten.<\/p>\n<p style=\"padding-left: 40px;\"><strong>9. Regeln f\u00fcr Ihren Inhalt<\/strong><\/p>\n<p>9.1&nbsp;&nbsp;&nbsp; Sie garantieren und sichern zu, dass Ihr Inhalt mit diesen allgemeinen Nutzungsbedingungen \u00fcbereinstimmen wird.<\/p>\n<p>9.2&nbsp;&nbsp;&nbsp; Ihr Inhalt darf nicht illegal oder ungesetzlich sein, darf nicht die gesetzlichen Rechte einer Person verletzen und darf nicht zu rechtlichen Schritten gegen eine Person f\u00fchren (in jedem Fall in jeder Gerichtsbarkeit und nach jedem anwendbaren Recht).<\/p>\n<p>9.3&nbsp;&nbsp;&nbsp; Ihr Inhalt und die Verwendung Ihres Inhalts durch uns in \u00dcbereinstimmung mit diesen allgemeinen Nutzungsbedingungen d\u00fcrfen Folgendes nicht:<\/p>\n<p>(a)&nbsp;&nbsp;&nbsp; verleumderisch oder b\u00f6swillig falsch sein,<\/p>\n<p>(b)&nbsp;&nbsp;&nbsp; obsz\u00f6n oder unanst\u00e4ndig sein,<\/p>\n<p>(c)&nbsp;&nbsp;&nbsp; ein Urheberrecht, ein moralisches Recht, ein Datenbankrecht, ein Markenrecht, ein Geschmacksmusterrecht, ein Recht auf Nachahmung oder ein anderes Recht an geistigem Eigentum verletzen,<\/p>\n<p>(d)&nbsp;&nbsp;&nbsp; das Recht auf Vertrauen, das Recht auf Privatsph\u00e4re oder das Recht gem\u00e4\u00df dem Datenschutzrecht verletzen,<\/p>\n<p>(e)&nbsp;&nbsp;&nbsp; eine fahrl\u00e4ssige Beratung darstellen oder eine fahrl\u00e4ssige Erkl\u00e4rung enthalten,<\/p>\n<p>(f)&nbsp;&nbsp;&nbsp; eine Aufforderung zur Begehung einer Straftat, eine Anleitung zur Begehung einer Straftat oder die F\u00f6rderung einer kriminellen T\u00e4tigkeit darstellen,<\/p>\n<p>(g)&nbsp;&nbsp;&nbsp; sich der Missachtung eines Gerichts schuldig gemacht oder einer gerichtlichen Anordnung zuwidergehandelt haben,<\/p>\n<p>(h)&nbsp;&nbsp;&nbsp; gegen die Rechtsvorschriften \u00fcber Rassenhass oder religi\u00f6se Diskriminierung versto\u00dfen,<\/p>\n<p>(i)&nbsp;&nbsp;&nbsp; blasphemisch sein,<\/p>\n<p>(j)&nbsp;&nbsp;&nbsp; gegen die Rechtsvorschriften \u00fcber Amtsgeheimnisse versto\u00dfen,<\/p>\n<p>(k)&nbsp;&nbsp;&nbsp; gegen eine vertragliche Verpflichtung gegen\u00fcber einer Person versto\u00dfen haben,<\/p>\n<p>(l)&nbsp;&nbsp;&nbsp; Gewalt in expliziter, grafischer oder grundloser Weise darstellen,<\/p>\n<p>(m)&nbsp;&nbsp;&nbsp; pornografisch, unz\u00fcchtig, anz\u00fcglich oder eindeutig sexuell sein,<\/p>\n<p>(n)&nbsp;&nbsp;&nbsp; unwahr, falsch, ungenau oder irref\u00fchrend sein,<\/p>\n<p>(o)&nbsp;&nbsp;&nbsp; aus Anweisungen, Ratschl\u00e4gen oder anderen Informationen bestehen oder diese enthalten, die, wenn sie befolgt werden, Krankheit, Verletzung oder Tod oder andere Verluste oder Sch\u00e4den verursachen k\u00f6nnen,<\/p>\n<p>(p)&nbsp;&nbsp;&nbsp; Spam darstellen,<\/p>\n<p>(q)&nbsp;&nbsp;&nbsp; beleidigend, t\u00e4uschend, betr\u00fcgerisch, bedrohend, missbr\u00e4uchlich, bel\u00e4stigend, asozial, bedrohlich, hasserf\u00fcllt, diskriminierend oder aufr\u00fchrerisch sein oder<\/p>\n<p>(r)&nbsp;&nbsp;&nbsp; Bel\u00e4stigung, Unannehmlichkeiten oder unn\u00f6tige \u00c4ngste f\u00fcr irgendeine Person verursachen.<\/p>\n<p style=\"padding-left: 40px;\"><strong>10. Beschr\u00e4nkte Gew\u00e4hrleistungen<\/strong><\/p>\n<p>10.1&nbsp; Wir geben keine Gew\u00e4hrleistung oder Zusicherung f\u00fcr Folgendes:<\/p>\n<p>(a)&nbsp;&nbsp;&nbsp; die Vollst\u00e4ndigkeit oder Richtigkeit der auf unserer Website ver\u00f6ffentlichten Informationen,<\/p>\n<p>(b)&nbsp;&nbsp;&nbsp; dass das Material auf der Website auf dem neuesten Stand ist,<\/p>\n<p>(c)&nbsp;&nbsp;&nbsp; dass die Website fehlerfrei funktionieren wird oder<\/p>\n<p>(d)&nbsp;&nbsp;&nbsp; dass die Website oder ein Dienst auf der Website verf\u00fcgbar bleiben wird.<\/p>\n<p>10.2&nbsp; Wir behalten uns das Recht vor, einige oder alle unserer Website-Dienste einzustellen oder zu \u00e4ndern und die Ver\u00f6ffentlichung unserer Website jederzeit nach unserem alleinigen Ermessen ohne Vorank\u00fcndigung oder Erkl\u00e4rung einzustellen; und sofern in diesen allgemeinen Nutzungsbedingungen nicht ausdr\u00fccklich etwas anderes vorgesehen ist, haben Sie bei der Einstellung oder \u00c4nderung von Website-Diensten oder wenn wir die Ver\u00f6ffentlichung der Website einstellen, keinen Anspruch auf eine Entsch\u00e4digung oder sonstige Zahlung.<\/p>\n<p>10.3&nbsp; Soweit dies nach geltendem Recht zul\u00e4ssig ist und vorbehaltlich Abschnitt 11.1, schlie\u00dfen wir alle Zusicherungen und Gew\u00e4hrleistungen in Bezug auf den Gegenstand dieser allgemeinen Nutzungsbedingungen, unsere Website und die Nutzung unserer Website aus.<\/p>\n<p><strong>11. Beschr\u00e4nkungen und Haftungsausschl\u00fcsse<\/strong><\/p>\n<p>11.1&nbsp; Nichts in diesen allgemeinen Nutzungsbedingungen wird:<\/p>\n<p>(a)&nbsp;&nbsp;&nbsp; die Haftung f\u00fcr Tod oder K\u00f6rperverletzung aufgrund von Fahrl\u00e4ssigkeit beschr\u00e4nken oder ausschlie\u00dfen,<\/p>\n<p>(b)&nbsp;&nbsp;&nbsp; die Haftung f\u00fcr Betrug oder arglistige T\u00e4uschung beschr\u00e4nken oder ausschlie\u00dfen,<\/p>\n<p>(c)&nbsp;&nbsp;&nbsp; die Haftung in einer Weise beschr\u00e4nken, die nach geltendem Recht nicht zul\u00e4ssig ist oder<\/p>\n<p>(d)&nbsp;&nbsp;&nbsp; Haftungen ausschlie\u00dfen, die nach geltendem Recht nicht ausgeschlossen werden d\u00fcrfen.<\/p>\n<p>11.2&nbsp; Die Haftungsbeschr\u00e4nkungen und -ausschl\u00fcsse, die in diesem Abschnitt 11 und an anderer Stelle in diesen allgemeinen Nutzungsbedingungen festgelegt sind:<\/p>\n<p>(a)&nbsp;&nbsp;&nbsp; unterliegen Abschnitt 11.1 und<\/p>\n<p>(b)&nbsp;&nbsp;&nbsp; regeln alle Haftungen, die sich aus diesen allgemeinen Nutzungsbedingungen ergeben oder sich auf den Gegenstand dieser Bedingungen beziehen, einschlie\u00dflich der Haftungen, die sich aus Vertr\u00e4gen, unerlaubten Handlungen (einschlie\u00dflich Fahrl\u00e4ssigkeit) und aus der Verletzung gesetzlicher Pflichten ergeben, sofern in diesen Bedingungen nicht ausdr\u00fccklich etwas anderes vorgesehen ist.<\/p>\n<p>11.3&nbsp; Soweit unsere Website und die Informationen und Dienstleistungen auf unserer Website kostenlos zur Verf\u00fcgung gestellt werden, haften wir nicht f\u00fcr Verluste oder Sch\u00e4den jeglicher Art.<\/p>\n<p>11.4&nbsp; Wir haften Ihnen gegen\u00fcber nicht f\u00fcr Verluste, die sich aus Ereignissen ergeben, die au\u00dferhalb unserer Kontrolle liegen.<\/p>\n<p>11.5&nbsp; Wir haften Ihnen gegen\u00fcber nicht f\u00fcr gesch\u00e4ftliche Verluste, einschlie\u00dflich (ohne Einschr\u00e4nkung) des Verlusts oder der Besch\u00e4digung von Gewinnen, Einkommen, Einnahmen, Nutzung, Produktion, erwarteten Einsparungen, Gesch\u00e4ften, Vertr\u00e4gen, Gesch\u00e4ftsm\u00f6glichkeiten oder Firmenwert.<\/p>\n<p>11.6&nbsp; Wir haften Ihnen gegen\u00fcber nicht f\u00fcr den Verlust oder die Besch\u00e4digung von Daten, Datenbanken oder Software.<\/p>\n<p>11.7&nbsp; Wir haften Ihnen gegen\u00fcber nicht f\u00fcr besondere, indirekte oder Folgesch\u00e4den oder Verluste.<\/p>\n<p>11.8&nbsp; Sie akzeptieren, dass wir ein Interesse daran haben, die pers\u00f6nliche Haftung unserer leitenden Angestellten und Mitarbeiter zu begrenzen, und in Anbetracht dieses Interesses erkennen Sie an, dass wir eine Gesellschaft mit beschr\u00e4nkter Haftung sind; Sie stimmen zu, dass Sie keine pers\u00f6nlichen Anspr\u00fcche gegen unsere leitenden Angestellten oder Mitarbeiter in Bezug auf Verluste, die Sie in Verbindung mit der Website oder diesen allgemeinen Nutzungsbedingungen erleiden, geltend machen werden (dies begrenzt selbstverst\u00e4ndlich nicht die Haftung der Gesellschaft mit beschr\u00e4nkter Haftung selbst f\u00fcr die Handlungen und Unterlassungen unserer leitenden Angestellten und Mitarbeiter oder schlie\u00dft sie aus).<\/p>\n<p style=\"padding-left: 40px;\"><strong>12. Verst\u00f6\u00dfe gegen diese Bestimmungen und allgemeinen Nutzungsbedingungen<\/strong><\/p>\n<p>12.1 Unbeschadet unserer sonstigen Rechte gem\u00e4\u00df diesen allgemeinen Nutzungsbedingungen k\u00f6nnen wir, wenn Sie diese Bedingungen in irgendeiner Weise verletzen, oder wenn wir den begr\u00fcndeten Verdacht haben, dass Sie diese Bedingungen in irgendeiner Weise verletzt haben, Folgendes tun:<\/p>\n<p>(a)&nbsp;&nbsp;&nbsp; Ihnen eine oder mehrere f\u00f6rmliche Mahnungen zukommen lassen,<\/p>\n<p>(b)&nbsp;&nbsp;&nbsp; Ihren Zugriff auf unsere Website vor\u00fcbergehend aussetzen,<\/p>\n<p>(c)&nbsp;&nbsp;&nbsp; Ihnen den Zugriff auf unsere Website dauerhaft untersagen,<\/p>\n<p>(d)&nbsp;&nbsp;&nbsp; Computer, die Ihre IP-Adresse verwenden, f\u00fcr den Zugriff auf unsere Website sperren,<\/p>\n<p>(e)&nbsp;&nbsp;&nbsp; uns mit einem oder allen Ihren Internetdienstanbietern in Verbindung zu setzen und zu verlangen, dass diese Ihren Zugang zu unserer Website sperren,<\/p>\n<p>(f)&nbsp;&nbsp;&nbsp; gerichtliche Schritte gegen Sie einleiten, sei es wegen Vertragsbruchs oder aus anderen Gr\u00fcnden, und\/oder<\/p>\n<p>(g)&nbsp;&nbsp;&nbsp; Ihr Konto auf unserer Website aussetzen oder l\u00f6schen.<\/p>\n<p>12.2&nbsp; Wenn wir Ihren Zugang zu unserer Website oder einem Teil unserer Website aussetzen oder verbieten oder sperren, d\u00fcrfen Sie keine Ma\u00dfnahmen ergreifen, um eine solche Aussetzung oder ein solches Verbot oder eine solche Sperrung zu umgehen (einschlie\u00dflich, aber nicht beschr\u00e4nkt auf die Erstellung und\/oder Verwendung eines anderen Kontos).<\/p>\n<p style=\"padding-left: 40px;\"><strong>13. Variation<\/strong><\/p>\n<p>13.1&nbsp; Wir k\u00f6nnen diese allgemeinen Nutzungsbedingungen von Zeit zu Zeit \u00e4ndern.<\/p>\n<p>13.2&nbsp; Die ge\u00e4nderten allgemeinen Nutzungsbedingungen gelten f\u00fcr die Nutzung unserer Website ab dem Datum der Ver\u00f6ffentlichung der ge\u00e4nderten Bedingungen auf der Website, und Sie verzichten hiermit auf jegliches Recht, von \u00c4nderungen dieser Bedingungen benachrichtigt zu werden oder ihnen zuzustimmen.<\/p>\n<p>13.3&nbsp; Wenn Sie Ihre ausdr\u00fcckliche Zustimmung zu diesen allgemeinen Nutzungsbedingungen gegeben haben, werden wir Sie um Ihre ausdr\u00fcckliche Zustimmung zu einer \u00dcberarbeitung dieser Bedingungen bitten; und wenn Sie Ihre ausdr\u00fcckliche Zustimmung zu den \u00fcberarbeiteten Bedingungen nicht innerhalb einer von uns festgelegten Frist geben, werden wir Ihr Konto auf der Website deaktivieren oder l\u00f6schen, und Sie m\u00fcssen die Nutzung der Website einstellen.<\/p>\n<p style=\"padding-left: 40px;\"><strong>14. Zuweisung<\/strong><\/p>\n<p>14.1&nbsp; Sie stimmen hiermit zu, dass wir unsere Rechte und\/oder Pflichten gem\u00e4\u00df diesen allgemeinen Nutzungsbedingungen abtreten, \u00fcbertragen, untervergeben oder anderweitig damit umgehen k\u00f6nnen.<\/p>\n<p>14.2&nbsp; Sie d\u00fcrfen ohne unsere vorherige schriftliche Zustimmung Ihre Rechte und\/oder Pflichten aus diesen allgemeinen Nutzungsbedingungen nicht abtreten, \u00fcbertragen, untervergeben oder anderweitig damit umgehen.<\/p>\n<p style=\"padding-left: 40px;\"><strong>15. Trennbarkeit<\/strong><\/p>\n<p>15.1&nbsp; Wird eine Bestimmung dieser allgemeinen Nutzungsbedingungen von einem Gericht oder einer anderen zust\u00e4ndigen Beh\u00f6rde f\u00fcr rechtswidrig und\/oder nicht durchsetzbar befunden, so bleiben die \u00fcbrigen Bestimmungen in Kraft.<\/p>\n<p>15.2&nbsp; Wenn eine ungesetzliche und\/oder nicht durchsetzbare Bestimmung dieser allgemeinen Nutzungsbedingungen rechtm\u00e4\u00dfig oder durchsetzbar w\u00e4re, wenn ein Teil davon gestrichen w\u00fcrde, gilt dieser Teil als gestrichen, und der Rest der Bestimmung bleibt in Kraft.<\/p>\n<p style=\"padding-left: 40px;\"><strong>16. Rechte Dritter<\/strong><\/p>\n<p>16.1&nbsp; Ein Vertrag unter diesen allgemeinen Nutzungsbedingungen ist zu unseren und Ihren Gunsten und ist nicht dazu bestimmt, Dritten zugute zu kommen oder von diesen durchsetzbar zu sein.<\/p>\n<p>16.2&nbsp; Die Aus\u00fcbung der Rechte der Parteien aus einem Vertrag nach diesen allgemeinen Nutzungsbedingungen ist nicht von der Zustimmung eines Dritten abh\u00e4ngig.<\/p>\n<p style=\"padding-left: 40px;\"><strong>17. Gesamte Vereinbarung<\/strong><\/p>\n<p>17.1&nbsp; Vorbehaltlich des Abschnitts 11.1 stellen diese allgemeinen Nutzungsbedingungen zusammen mit unserer Datenschutz- und Cookie-Richtlinie die gesamte Vereinbarung zwischen Ihnen und uns in Bezug auf die Nutzung unserer Website dar und ersetzen alle fr\u00fcheren Vereinbarungen zwischen Ihnen und uns in Bezug auf die Nutzung unserer Website.<\/p>\n<p style=\"padding-left: 40px;\"><strong>18. Recht und Gerichtsbarkeit<\/strong><\/p>\n<p>18.1&nbsp; Die vorliegenden allgemeinen Nutzungsbedingungen unterliegen spanischem Recht und sind nach diesem auszulegen.<\/p>\n<p>18.2&nbsp; F\u00fcr alle Streitigkeiten im Zusammenhang mit den vorliegenden allgemeinen Nutzungsbedingungen gilt die ausschlie\u00dfliche Zust\u00e4ndigkeit der spanischen Gerichte.<\/p>\n<p style=\"padding-left: 40px;\"><strong>19. Gesetzliche und regulatorische Offenlegungen<\/strong><\/p>\n<p>19.1&nbsp; Wir sind im Handelsregister von Madrid eingetragen, Band: 29.460, Folio: 132, Blatt: M-53030.<\/p>\n<p>19.2&nbsp; Wir sind als German Translation Unit S.L. in Spanien registriert.<\/p>\n<p>19.3&nbsp; Unsere Umsatzsteuer-Identifikationsnummer lautet ESB86375557.<\/p>\n<p><strong>20. Informationen \u00fcber das Unternehmen<\/strong><\/p>\n<p>20.1&nbsp; Diese Website ist Eigentum und wird betrieben von German Translation Unit S.L.<\/p>\n<p>20.2&nbsp; Wir sind in Spanien registriert und unser eingetragener Sitz befindet sich in der Calle Zurbano 45, 1. Stock, 28010 Madrid.<\/p>\n<p>20.3&nbsp; Unser Hauptgesch\u00e4ftssitz befindet sich in der Calle Zurbano 45, 1. Stock, 28010 Madrid.<\/p>\n<p>20.4&nbsp; Sie k\u00f6nnen uns wie folgt kontaktieren:<\/p>\n<p>(a)&nbsp;&nbsp;&nbsp; per Post an die oben angegebene Postanschrift,<\/p>\n<p>(b)&nbsp;&nbsp;&nbsp; \u00fcber unser Kontaktformular auf der Website,<\/p>\n<p>(c)&nbsp;&nbsp;&nbsp; telefonisch unter der auf unserer Website ver\u00f6ffentlichten Kontaktnummer oder<\/p>\n<p>(d)&nbsp;&nbsp;&nbsp; per E-Mail unter Verwendung der auf unserer Website ver\u00f6ffentlichten E-Mail-Adresse.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ee61d16 elementor-hidden-mobile\" data-id=\"ee61d16\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Allgemeine Nutzungsbedingungen 1.&nbsp; &nbsp; &nbsp; Einf\u00fchrung 1.1&nbsp;&nbsp;&nbsp; Diese allgemeinen Nutzungsbedingungen regeln Ihre Nutzung unserer Website. 1.2&nbsp;&nbsp;&nbsp; Durch die Nutzung unserer Website akzeptieren Sie diese allgemeinen Nutzungsbedingungen in vollem Umfang; dementsprechend d\u00fcrfen Sie unsere Website nicht nutzen, wenn Sie mit diesen Bedingungen oder einem Teil dieser Bedingungen nicht einverstanden sind. 1.3&nbsp;&nbsp;&nbsp; Wenn Sie sich auf unserer &#8230; <a title=\"Allgemeine Nutzungsbedingungen\" class=\"read-more\" href=\"https:\/\/gtu.agency\/de\/allgemeine-nutzungsbedingungen\/\" aria-label=\"Mehr Informationen \u00fcber Allgemeine Nutzungsbedingungen\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1944","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Allgemeine Nutzungsbedingungen - GTU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gtu.agency\/de\/allgemeine-nutzungsbedingungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Allgemeine Nutzungsbedingungen - GTU\" \/>\n<meta property=\"og:description\" content=\"Allgemeine Nutzungsbedingungen 1.&nbsp; &nbsp; &nbsp; Einf\u00fchrung 1.1&nbsp;&nbsp;&nbsp; Diese allgemeinen Nutzungsbedingungen regeln Ihre Nutzung unserer Website. 1.2&nbsp;&nbsp;&nbsp; Durch die Nutzung unserer Website akzeptieren Sie diese allgemeinen Nutzungsbedingungen in vollem Umfang; dementsprechend d\u00fcrfen Sie unsere Website nicht nutzen, wenn Sie mit diesen Bedingungen oder einem Teil dieser Bedingungen nicht einverstanden sind. 1.3&nbsp;&nbsp;&nbsp; Wenn Sie sich auf unserer ... Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gtu.agency\/de\/allgemeine-nutzungsbedingungen\/\" \/>\n<meta property=\"og:site_name\" content=\"GTU\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-11T08:29:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"16\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gtu.agency\\\/de\\\/allgemeine-nutzungsbedingungen\\\/\",\"url\":\"https:\\\/\\\/gtu.agency\\\/de\\\/allgemeine-nutzungsbedingungen\\\/\",\"name\":\"Allgemeine Nutzungsbedingungen - GTU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gtu.agency\\\/#website\"},\"datePublished\":\"2022-06-23T13:54:49+00:00\",\"dateModified\":\"2022-07-11T08:29:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gtu.agency\\\/de\\\/allgemeine-nutzungsbedingungen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gtu.agency\\\/de\\\/allgemeine-nutzungsbedingungen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gtu.agency\\\/de\\\/allgemeine-nutzungsbedingungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/gtu.agency\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Allgemeine Nutzungsbedingungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gtu.agency\\\/#website\",\"url\":\"https:\\\/\\\/gtu.agency\\\/\",\"name\":\"GTU\",\"description\":\"Translation Agency\",\"publisher\":{\"@id\":\"https:\\\/\\\/gtu.agency\\\/#\\\/schema\\\/person\\\/f0aa70d9acb47d7aeba5fbcf24aaf0ba\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gtu.agency\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/gtu.agency\\\/#\\\/schema\\\/person\\\/f0aa70d9acb47d7aeba5fbcf24aaf0ba\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/gtu.agency\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/icon-gtu.svg\",\"url\":\"https:\\\/\\\/gtu.agency\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/icon-gtu.svg\",\"contentUrl\":\"https:\\\/\\\/gtu.agency\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/icon-gtu.svg\",\"width\":120,\"height\":65,\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/gtu.agency\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/icon-gtu.svg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Allgemeine Nutzungsbedingungen - GTU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gtu.agency\/de\/allgemeine-nutzungsbedingungen\/","og_locale":"de_DE","og_type":"article","og_title":"Allgemeine Nutzungsbedingungen - GTU","og_description":"Allgemeine Nutzungsbedingungen 1.&nbsp; &nbsp; &nbsp; Einf\u00fchrung 1.1&nbsp;&nbsp;&nbsp; Diese allgemeinen Nutzungsbedingungen regeln Ihre Nutzung unserer Website. 1.2&nbsp;&nbsp;&nbsp; Durch die Nutzung unserer Website akzeptieren Sie diese allgemeinen Nutzungsbedingungen in vollem Umfang; dementsprechend d\u00fcrfen Sie unsere Website nicht nutzen, wenn Sie mit diesen Bedingungen oder einem Teil dieser Bedingungen nicht einverstanden sind. 1.3&nbsp;&nbsp;&nbsp; Wenn Sie sich auf unserer ... Weiterlesen","og_url":"https:\/\/gtu.agency\/de\/allgemeine-nutzungsbedingungen\/","og_site_name":"GTU","article_modified_time":"2022-07-11T08:29:18+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"16\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gtu.agency\/de\/allgemeine-nutzungsbedingungen\/","url":"https:\/\/gtu.agency\/de\/allgemeine-nutzungsbedingungen\/","name":"Allgemeine Nutzungsbedingungen - GTU","isPartOf":{"@id":"https:\/\/gtu.agency\/#website"},"datePublished":"2022-06-23T13:54:49+00:00","dateModified":"2022-07-11T08:29:18+00:00","breadcrumb":{"@id":"https:\/\/gtu.agency\/de\/allgemeine-nutzungsbedingungen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gtu.agency\/de\/allgemeine-nutzungsbedingungen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gtu.agency\/de\/allgemeine-nutzungsbedingungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/gtu.agency\/de\/"},{"@type":"ListItem","position":2,"name":"Allgemeine Nutzungsbedingungen"}]},{"@type":"WebSite","@id":"https:\/\/gtu.agency\/#website","url":"https:\/\/gtu.agency\/","name":"GTU","description":"Translation Agency","publisher":{"@id":"https:\/\/gtu.agency\/#\/schema\/person\/f0aa70d9acb47d7aeba5fbcf24aaf0ba"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gtu.agency\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/gtu.agency\/#\/schema\/person\/f0aa70d9acb47d7aeba5fbcf24aaf0ba","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/03\/icon-gtu.svg","url":"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/03\/icon-gtu.svg","contentUrl":"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/03\/icon-gtu.svg","width":120,"height":65,"caption":"admin"},"logo":{"@id":"https:\/\/gtu.agency\/wp-content\/uploads\/2022\/03\/icon-gtu.svg"}}]}},"_links":{"self":[{"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/pages\/1944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/comments?post=1944"}],"version-history":[{"count":3,"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/pages\/1944\/revisions"}],"predecessor-version":[{"id":2062,"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/pages\/1944\/revisions\/2062"}],"wp:attachment":[{"href":"https:\/\/gtu.agency\/de\/wp-json\/wp\/v2\/media?parent=1944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}